{"id":401,"count":1,"description":"","link":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/","name":"Zermatt","slug":"zermatt-es","taxonomy":"country_city","parent":374,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zermatt Archives - V1 Retreats<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zermatt Archives - V1 Retreats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/\" \/>\n<meta property=\"og:site_name\" content=\"V1 Retreats\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/\",\"url\":\"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/\",\"name\":\"Zermatt Archives - V1 Retreats\",\"isPartOf\":{\"@id\":\"https:\/\/v1-retreats.com\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/v1-retreats.com\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zermatt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/v1-retreats.com\/es\/#website\",\"url\":\"https:\/\/v1-retreats.com\/es\/\",\"name\":\"V1 Retreats\",\"description\":\"Relax. Detox. Recover.\",\"publisher\":{\"@id\":\"https:\/\/v1-retreats.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/v1-retreats.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/v1-retreats.com\/es\/#organization\",\"name\":\"V1 Retreats\",\"url\":\"https:\/\/v1-retreats.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/v1-retreats.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/v1-retreats.com\/wp-content\/uploads\/2024\/04\/v1retreat-logo.svg\",\"contentUrl\":\"https:\/\/v1-retreats.com\/wp-content\/uploads\/2024\/04\/v1retreat-logo.svg\",\"width\":193,\"height\":23,\"caption\":\"V1 Retreats\"},\"image\":{\"@id\":\"https:\/\/v1-retreats.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zermatt Archives - V1 Retreats","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/","og_locale":"es_ES","og_type":"article","og_title":"Zermatt Archives - V1 Retreats","og_url":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/","og_site_name":"V1 Retreats","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/","url":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/","name":"Zermatt Archives - V1 Retreats","isPartOf":{"@id":"https:\/\/v1-retreats.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/v1-retreats.com\/es\/destination\/zermatt-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/v1-retreats.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Zermatt"}]},{"@type":"WebSite","@id":"https:\/\/v1-retreats.com\/es\/#website","url":"https:\/\/v1-retreats.com\/es\/","name":"V1 Retreats","description":"Relax. Detox. Recover.","publisher":{"@id":"https:\/\/v1-retreats.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/v1-retreats.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/v1-retreats.com\/es\/#organization","name":"V1 Retreats","url":"https:\/\/v1-retreats.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/v1-retreats.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/v1-retreats.com\/wp-content\/uploads\/2024\/04\/v1retreat-logo.svg","contentUrl":"https:\/\/v1-retreats.com\/wp-content\/uploads\/2024\/04\/v1retreat-logo.svg","width":193,"height":23,"caption":"V1 Retreats"},"image":{"@id":"https:\/\/v1-retreats.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/v1-retreats.com\/es\/wp-json\/wp\/v2\/country_city\/401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/v1-retreats.com\/es\/wp-json\/wp\/v2\/country_city"}],"about":[{"href":"https:\/\/v1-retreats.com\/es\/wp-json\/wp\/v2\/taxonomies\/country_city"}],"up":[{"embeddable":true,"href":"https:\/\/v1-retreats.com\/es\/wp-json\/wp\/v2\/country_city\/374"}],"wp:post_type":[{"href":"https:\/\/v1-retreats.com\/es\/wp-json\/wp\/v2\/retreat?country_city=401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}